{"id":2290,"date":"2024-11-12T17:26:53","date_gmt":"2024-11-12T16:26:53","guid":{"rendered":"https:\/\/www.alterre-asso.org\/?p=2290"},"modified":"2024-11-12T17:31:35","modified_gmt":"2024-11-12T16:31:35","slug":"loperation-desinformation-de-la-ccrc-poursuit-son-cours","status":"publish","type":"post","link":"https:\/\/www.alterre-asso.org\/index.php\/2024\/11\/12\/loperation-desinformation-de-la-ccrc-poursuit-son-cours\/","title":{"rendered":"L&rsquo;op\u00e9ration d\u00e9sinformation de la CCRC poursuit son cours"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large is-resized\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.alterre-asso.org\/wp-content\/uploads\/2024\/11\/Actus_SiteDeviation-1024x768.jpg\" alt=\"\" class=\"wp-image-2294\" style=\"width:413px;height:auto\" srcset=\"https:\/\/www.alterre-asso.org\/wp-content\/uploads\/2024\/11\/Actus_SiteDeviation-1024x768.jpg 1024w, https:\/\/www.alterre-asso.org\/wp-content\/uploads\/2024\/11\/Actus_SiteDeviation-300x225.jpg 300w, https:\/\/www.alterre-asso.org\/wp-content\/uploads\/2024\/11\/Actus_SiteDeviation-768x576.jpg 768w, https:\/\/www.alterre-asso.org\/wp-content\/uploads\/2024\/11\/Actus_SiteDeviation-1536x1152.jpg 1536w, https:\/\/www.alterre-asso.org\/wp-content\/uploads\/2024\/11\/Actus_SiteDeviation.jpg 2013w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Cette semaine de novembre 2024, les habitants de Saint P\u00e9ray et alentours ont re\u00e7u dans leur boite aux lettre un document \u00e9dit\u00e9 par la Communaut\u00e9 de Communes de Rh\u00f4ne Crussol visant \u00e0 justifier le projet de \u00ab d\u00e9viation de Saint-P\u00e9ray \u00bb.&nbsp;<\/p>\n\n\n\n<p>La publication de ce document intervient juste au moment o\u00f9 la CCRC commet de nombreuses irr\u00e9gularit\u00e9s dans la r\u00e9alisation des travaux : exposition d\u00e9lib\u00e9r\u00e9 des ouvriers \u00e0 l&rsquo;amiante, destruction d&rsquo;habitat d&rsquo;esp\u00e8ces prot\u00e9g\u00e9es, arbres arrach\u00e9s.. autant de point qui ne figurent pas dans ce document.&nbsp;<\/p>\n\n\n\n<p>Au del\u00e0 de ces irr\u00e9gularit\u00e9s ALTERRE alerte sur le fait que ce document est entach\u00e9 de nombreuses approximations et omissions : il induit la population en erreur.<\/p>\n\n\n\n<p><strong>Sous<\/strong><strong>&#8211;<\/strong><strong>estimation des couts<\/strong><\/p>\n\n\n\n<p>La plus \u00e9vidente est financi\u00e8re : le co\u00fbt annonc\u00e9 ne comprend pas le pont sur le Mialan, un \u00ab oubli \u00bb \u00e0 3 millions d\u2019euros\u2026 En effet, le co\u00fbt indiqu\u00e9 est uniquement celui de \u00ab la section 3 \u00bb. Or, selon un curieux tron\u00e7onnage du projet que montre les documents financiers transmis en annexe, le pont sur le Mialan correspond \u00e0 \u00ab la section 2 \u00bb. Cette pratique qui consiste \u00e0 \u00ab\u00a0oublier\u00a0\u00bb les ponts n&rsquo;est pas une premi\u00e8re. D\u00e9j\u00e0 lors de l&rsquo;enqu\u00eate publique l&rsquo;enqu\u00eateur avait point\u00e9 un manquement dans le budget : dans les documents fournis \u00e0 la population, il manquait d\u00e9j\u00e0 un autre pont, celui sous la voie ferr\u00e9e, une broutille de 6 millions d\u2019euros.<\/p>\n\n\n\n<p><strong>Plans erron\u00e9s<\/strong><\/p>\n\n\n\n<p>Autre grossi\u00e8re \u00ab erreur \u00bb : la carte publi\u00e9e n\u2019est pas conforme aux documents d\u2019urbanisme et au SCOT ! La CCRC tente de faire croire que toute la Plaine est une zone prot\u00e9g\u00e9e alors qu\u2019elle a d\u00e9j\u00e0 adopt\u00e9 et formalis\u00e9 dans ses propres documents un trac\u00e9 pour la future route vers le \u00ab 3e pont \u00bb qui doit traverser le Rh\u00f4ne au niveau du barrage de Bourg-les-Valence.<\/p>\n\n\n\n<p><strong>\u00ab\u00a0Fluidifier le traffic\u00a0\u00bb ?!<\/strong><\/p>\n\n\n\n<p>La CCRC affirme que cette d\u00e9viation va permettre de r\u00e9duire les bouchons quotidiens sur Saint P\u00e9ray. Les propres estimations de la CCRC diffus\u00e9s lors de l&rsquo;enqu\u00eate publique estiment pourtant que d&rsquo;ici 15 ans, le traffic sera de 20 \u00e0 30 % sup\u00e9rieurs sur les sections d\u00e9j\u00e0 congestionn\u00e9es AVEC la d\u00e9viation. Les \u00e9tudes de transports confirm\u00e9es par des observations de terrain partout en France montrent qu&rsquo;augmenter la capacit\u00e9 routi\u00e8re &#8211; m\u00eame en ajoutant des pistes cyclables &#8211; ne permet pas de r\u00e9duire le traffic.&nbsp;<\/p>\n\n\n\n<p>L&rsquo;association ALTERRE rappelle qu&rsquo;aucune alternative n&rsquo;a \u00e9t\u00e9 \u00e9tudi\u00e9e par les \u00e9lus pour r\u00e9pondre aux besoins de transport de la population sans pour autant construire cette nouvelle route. Et pourtant les solutions existent et sont mises en oeuvre avec succ\u00e8s dans d&rsquo;autres communes : ouverture de la gare de Saint-P\u00e9ray, augmentation de l&rsquo;offre de transport en commun, d\u00e9veloppement des pistes cyclables, offre de covoiturage, plaidoyer pour le ferroutage des camions, etc.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Fin octobre Alterre a publi\u00e9 un document qui reprend les \u00e9l\u00e9ments cl\u00e9s du projet de d\u00e9viation et \u00e9voque des alternatives possibles. Il est disponible ici : <\/p>\n\n\n\n<p><a href=\"https:\/\/drive.proton.me\/urls\/C8F1542AK0#d8IiqMuzoO4d\">https:\/\/drive.proton.me\/urls\/C8F1542AK0#d8IiqMuzoO4d<\/a><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"720\" height=\"1024\" src=\"https:\/\/www.alterre-asso.org\/wp-content\/uploads\/2024\/11\/Capture-decran-2024-11-12-a-17.26.01-720x1024.png\" alt=\"\" class=\"wp-image-2291\" srcset=\"https:\/\/www.alterre-asso.org\/wp-content\/uploads\/2024\/11\/Capture-decran-2024-11-12-a-17.26.01-720x1024.png 720w, https:\/\/www.alterre-asso.org\/wp-content\/uploads\/2024\/11\/Capture-decran-2024-11-12-a-17.26.01-211x300.png 211w, https:\/\/www.alterre-asso.org\/wp-content\/uploads\/2024\/11\/Capture-decran-2024-11-12-a-17.26.01-768x1092.png 768w, https:\/\/www.alterre-asso.org\/wp-content\/uploads\/2024\/11\/Capture-decran-2024-11-12-a-17.26.01-1080x1536.png 1080w, https:\/\/www.alterre-asso.org\/wp-content\/uploads\/2024\/11\/Capture-decran-2024-11-12-a-17.26.01.png 1110w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/figure>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cette semaine de novembre 2024, les habitants de Saint P\u00e9ray et alentours ont re\u00e7u dans leur boite aux lettre un document \u00e9dit\u00e9 par la Communaut\u00e9 de Communes de Rh\u00f4ne Crussol visant \u00e0 justifier le projet de \u00ab d\u00e9viation de Saint-P\u00e9ray \u00bb.&nbsp; La publication de ce document intervient juste au moment o\u00f9 la CCRC commet de [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":2294,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[3],"tags":[],"class_list":["post-2290","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articles","entry","has-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>L&#039;op\u00e9ration d\u00e9sinformation de la CCRC poursuit son cours - Alterre<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.alterre-asso.org\/index.php\/2024\/11\/12\/loperation-desinformation-de-la-ccrc-poursuit-son-cours\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;op\u00e9ration d\u00e9sinformation de la CCRC poursuit son cours - Alterre\" \/>\n<meta property=\"og:description\" content=\"Cette semaine de novembre 2024, les habitants de Saint P\u00e9ray et alentours ont re\u00e7u dans leur boite aux lettre un document \u00e9dit\u00e9 par la Communaut\u00e9 de Communes de Rh\u00f4ne Crussol visant \u00e0 justifier le projet de \u00ab d\u00e9viation de Saint-P\u00e9ray \u00bb.&nbsp; La publication de ce document intervient juste au moment o\u00f9 la CCRC commet de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.alterre-asso.org\/index.php\/2024\/11\/12\/loperation-desinformation-de-la-ccrc-poursuit-son-cours\/\" \/>\n<meta property=\"og:site_name\" content=\"Alterre\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AlternativesaladeviationdeSaintPeray\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-12T16:26:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-12T16:31:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.alterre-asso.org\/wp-content\/uploads\/2024\/11\/Actus_SiteDeviation.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2013\" \/>\n\t<meta property=\"og:image:height\" content=\"1510\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alterre\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alterre\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.alterre-asso.org\/index.php\/2024\/11\/12\/loperation-desinformation-de-la-ccrc-poursuit-son-cours\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.alterre-asso.org\/index.php\/2024\/11\/12\/loperation-desinformation-de-la-ccrc-poursuit-son-cours\/\"},\"author\":{\"name\":\"Alterre\",\"@id\":\"https:\/\/www.alterre-asso.org\/#\/schema\/person\/23502c44ac024a1656bdb5d1cdae3e50\"},\"headline\":\"L&rsquo;op\u00e9ration d\u00e9sinformation de la CCRC poursuit son cours\",\"datePublished\":\"2024-11-12T16:26:53+00:00\",\"dateModified\":\"2024-11-12T16:31:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.alterre-asso.org\/index.php\/2024\/11\/12\/loperation-desinformation-de-la-ccrc-poursuit-son-cours\/\"},\"wordCount\":531,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.alterre-asso.org\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.alterre-asso.org\/index.php\/2024\/11\/12\/loperation-desinformation-de-la-ccrc-poursuit-son-cours\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.alterre-asso.org\/wp-content\/uploads\/2024\/11\/Actus_SiteDeviation.jpg\",\"articleSection\":[\"Articles\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.alterre-asso.org\/index.php\/2024\/11\/12\/loperation-desinformation-de-la-ccrc-poursuit-son-cours\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.alterre-asso.org\/index.php\/2024\/11\/12\/loperation-desinformation-de-la-ccrc-poursuit-son-cours\/\",\"url\":\"https:\/\/www.alterre-asso.org\/index.php\/2024\/11\/12\/loperation-desinformation-de-la-ccrc-poursuit-son-cours\/\",\"name\":\"L'op\u00e9ration d\u00e9sinformation de la CCRC poursuit son cours - Alterre\",\"isPartOf\":{\"@id\":\"https:\/\/www.alterre-asso.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.alterre-asso.org\/index.php\/2024\/11\/12\/loperation-desinformation-de-la-ccrc-poursuit-son-cours\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.alterre-asso.org\/index.php\/2024\/11\/12\/loperation-desinformation-de-la-ccrc-poursuit-son-cours\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.alterre-asso.org\/wp-content\/uploads\/2024\/11\/Actus_SiteDeviation.jpg\",\"datePublished\":\"2024-11-12T16:26:53+00:00\",\"dateModified\":\"2024-11-12T16:31:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.alterre-asso.org\/index.php\/2024\/11\/12\/loperation-desinformation-de-la-ccrc-poursuit-son-cours\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.alterre-asso.org\/index.php\/2024\/11\/12\/loperation-desinformation-de-la-ccrc-poursuit-son-cours\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.alterre-asso.org\/index.php\/2024\/11\/12\/loperation-desinformation-de-la-ccrc-poursuit-son-cours\/#primaryimage\",\"url\":\"https:\/\/www.alterre-asso.org\/wp-content\/uploads\/2024\/11\/Actus_SiteDeviation.jpg\",\"contentUrl\":\"https:\/\/www.alterre-asso.org\/wp-content\/uploads\/2024\/11\/Actus_SiteDeviation.jpg\",\"width\":2013,\"height\":1510,\"caption\":\"Bulletin d'information de la CCRC\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.alterre-asso.org\/index.php\/2024\/11\/12\/loperation-desinformation-de-la-ccrc-poursuit-son-cours\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.alterre-asso.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&rsquo;op\u00e9ration d\u00e9sinformation de la CCRC poursuit son cours\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.alterre-asso.org\/#website\",\"url\":\"https:\/\/www.alterre-asso.org\/\",\"name\":\"Alterre\",\"description\":\"alternatives \u00e0 la d\u00e9viation de Saint-P\u00e9ray\",\"publisher\":{\"@id\":\"https:\/\/www.alterre-asso.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.alterre-asso.org\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.alterre-asso.org\/#organization\",\"name\":\"Alterre\",\"url\":\"https:\/\/www.alterre-asso.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.alterre-asso.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.alterre-asso.org\/wp-content\/uploads\/2023\/11\/cropped-cropped-logo.jpg\",\"contentUrl\":\"https:\/\/www.alterre-asso.org\/wp-content\/uploads\/2023\/11\/cropped-cropped-logo.jpg\",\"width\":240,\"height\":243,\"caption\":\"Alterre\"},\"image\":{\"@id\":\"https:\/\/www.alterre-asso.org\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/AlternativesaladeviationdeSaintPeray\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.alterre-asso.org\/#\/schema\/person\/23502c44ac024a1656bdb5d1cdae3e50\",\"name\":\"Alterre\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.alterre-asso.org\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e4cfcc608545597246d25c6d1767738d494c63a6d88ccd0ec66123afcc10a05e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e4cfcc608545597246d25c6d1767738d494c63a6d88ccd0ec66123afcc10a05e?s=96&d=mm&r=g\",\"caption\":\"Alterre\"},\"url\":\"https:\/\/www.alterre-asso.org\/index.php\/author\/alterre\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'op\u00e9ration d\u00e9sinformation de la CCRC poursuit son cours - Alterre","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.alterre-asso.org\/index.php\/2024\/11\/12\/loperation-desinformation-de-la-ccrc-poursuit-son-cours\/","og_locale":"fr_FR","og_type":"article","og_title":"L'op\u00e9ration d\u00e9sinformation de la CCRC poursuit son cours - Alterre","og_description":"Cette semaine de novembre 2024, les habitants de Saint P\u00e9ray et alentours ont re\u00e7u dans leur boite aux lettre un document \u00e9dit\u00e9 par la Communaut\u00e9 de Communes de Rh\u00f4ne Crussol visant \u00e0 justifier le projet de \u00ab d\u00e9viation de Saint-P\u00e9ray \u00bb.&nbsp; La publication de ce document intervient juste au moment o\u00f9 la CCRC commet de [&hellip;]","og_url":"https:\/\/www.alterre-asso.org\/index.php\/2024\/11\/12\/loperation-desinformation-de-la-ccrc-poursuit-son-cours\/","og_site_name":"Alterre","article_publisher":"https:\/\/www.facebook.com\/AlternativesaladeviationdeSaintPeray\/","article_published_time":"2024-11-12T16:26:53+00:00","article_modified_time":"2024-11-12T16:31:35+00:00","og_image":[{"width":2013,"height":1510,"url":"https:\/\/www.alterre-asso.org\/wp-content\/uploads\/2024\/11\/Actus_SiteDeviation.jpg","type":"image\/jpeg"}],"author":"Alterre","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Alterre","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.alterre-asso.org\/index.php\/2024\/11\/12\/loperation-desinformation-de-la-ccrc-poursuit-son-cours\/#article","isPartOf":{"@id":"https:\/\/www.alterre-asso.org\/index.php\/2024\/11\/12\/loperation-desinformation-de-la-ccrc-poursuit-son-cours\/"},"author":{"name":"Alterre","@id":"https:\/\/www.alterre-asso.org\/#\/schema\/person\/23502c44ac024a1656bdb5d1cdae3e50"},"headline":"L&rsquo;op\u00e9ration d\u00e9sinformation de la CCRC poursuit son cours","datePublished":"2024-11-12T16:26:53+00:00","dateModified":"2024-11-12T16:31:35+00:00","mainEntityOfPage":{"@id":"https:\/\/www.alterre-asso.org\/index.php\/2024\/11\/12\/loperation-desinformation-de-la-ccrc-poursuit-son-cours\/"},"wordCount":531,"commentCount":0,"publisher":{"@id":"https:\/\/www.alterre-asso.org\/#organization"},"image":{"@id":"https:\/\/www.alterre-asso.org\/index.php\/2024\/11\/12\/loperation-desinformation-de-la-ccrc-poursuit-son-cours\/#primaryimage"},"thumbnailUrl":"https:\/\/www.alterre-asso.org\/wp-content\/uploads\/2024\/11\/Actus_SiteDeviation.jpg","articleSection":["Articles"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.alterre-asso.org\/index.php\/2024\/11\/12\/loperation-desinformation-de-la-ccrc-poursuit-son-cours\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.alterre-asso.org\/index.php\/2024\/11\/12\/loperation-desinformation-de-la-ccrc-poursuit-son-cours\/","url":"https:\/\/www.alterre-asso.org\/index.php\/2024\/11\/12\/loperation-desinformation-de-la-ccrc-poursuit-son-cours\/","name":"L'op\u00e9ration d\u00e9sinformation de la CCRC poursuit son cours - Alterre","isPartOf":{"@id":"https:\/\/www.alterre-asso.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.alterre-asso.org\/index.php\/2024\/11\/12\/loperation-desinformation-de-la-ccrc-poursuit-son-cours\/#primaryimage"},"image":{"@id":"https:\/\/www.alterre-asso.org\/index.php\/2024\/11\/12\/loperation-desinformation-de-la-ccrc-poursuit-son-cours\/#primaryimage"},"thumbnailUrl":"https:\/\/www.alterre-asso.org\/wp-content\/uploads\/2024\/11\/Actus_SiteDeviation.jpg","datePublished":"2024-11-12T16:26:53+00:00","dateModified":"2024-11-12T16:31:35+00:00","breadcrumb":{"@id":"https:\/\/www.alterre-asso.org\/index.php\/2024\/11\/12\/loperation-desinformation-de-la-ccrc-poursuit-son-cours\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.alterre-asso.org\/index.php\/2024\/11\/12\/loperation-desinformation-de-la-ccrc-poursuit-son-cours\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.alterre-asso.org\/index.php\/2024\/11\/12\/loperation-desinformation-de-la-ccrc-poursuit-son-cours\/#primaryimage","url":"https:\/\/www.alterre-asso.org\/wp-content\/uploads\/2024\/11\/Actus_SiteDeviation.jpg","contentUrl":"https:\/\/www.alterre-asso.org\/wp-content\/uploads\/2024\/11\/Actus_SiteDeviation.jpg","width":2013,"height":1510,"caption":"Bulletin d'information de la CCRC"},{"@type":"BreadcrumbList","@id":"https:\/\/www.alterre-asso.org\/index.php\/2024\/11\/12\/loperation-desinformation-de-la-ccrc-poursuit-son-cours\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.alterre-asso.org\/"},{"@type":"ListItem","position":2,"name":"L&rsquo;op\u00e9ration d\u00e9sinformation de la CCRC poursuit son cours"}]},{"@type":"WebSite","@id":"https:\/\/www.alterre-asso.org\/#website","url":"https:\/\/www.alterre-asso.org\/","name":"Alterre","description":"alternatives \u00e0 la d\u00e9viation de Saint-P\u00e9ray","publisher":{"@id":"https:\/\/www.alterre-asso.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.alterre-asso.org\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.alterre-asso.org\/#organization","name":"Alterre","url":"https:\/\/www.alterre-asso.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.alterre-asso.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.alterre-asso.org\/wp-content\/uploads\/2023\/11\/cropped-cropped-logo.jpg","contentUrl":"https:\/\/www.alterre-asso.org\/wp-content\/uploads\/2023\/11\/cropped-cropped-logo.jpg","width":240,"height":243,"caption":"Alterre"},"image":{"@id":"https:\/\/www.alterre-asso.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AlternativesaladeviationdeSaintPeray\/"]},{"@type":"Person","@id":"https:\/\/www.alterre-asso.org\/#\/schema\/person\/23502c44ac024a1656bdb5d1cdae3e50","name":"Alterre","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.alterre-asso.org\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e4cfcc608545597246d25c6d1767738d494c63a6d88ccd0ec66123afcc10a05e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e4cfcc608545597246d25c6d1767738d494c63a6d88ccd0ec66123afcc10a05e?s=96&d=mm&r=g","caption":"Alterre"},"url":"https:\/\/www.alterre-asso.org\/index.php\/author\/alterre\/"}]}},"_links":{"self":[{"href":"https:\/\/www.alterre-asso.org\/index.php\/wp-json\/wp\/v2\/posts\/2290","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.alterre-asso.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.alterre-asso.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.alterre-asso.org\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.alterre-asso.org\/index.php\/wp-json\/wp\/v2\/comments?post=2290"}],"version-history":[{"count":2,"href":"https:\/\/www.alterre-asso.org\/index.php\/wp-json\/wp\/v2\/posts\/2290\/revisions"}],"predecessor-version":[{"id":2295,"href":"https:\/\/www.alterre-asso.org\/index.php\/wp-json\/wp\/v2\/posts\/2290\/revisions\/2295"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.alterre-asso.org\/index.php\/wp-json\/wp\/v2\/media\/2294"}],"wp:attachment":[{"href":"https:\/\/www.alterre-asso.org\/index.php\/wp-json\/wp\/v2\/media?parent=2290"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.alterre-asso.org\/index.php\/wp-json\/wp\/v2\/categories?post=2290"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.alterre-asso.org\/index.php\/wp-json\/wp\/v2\/tags?post=2290"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}